{"id":13355,"date":"2022-05-05T09:53:22","date_gmt":"2022-05-05T09:53:22","guid":{"rendered":"https:\/\/uet.edu.al\/?p=13355"},"modified":"2022-05-05T14:25:46","modified_gmt":"2022-05-05T14:25:46","slug":"klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor","status":"publish","type":"post","link":"https:\/\/uet.edu.al\/en\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/","title":{"rendered":"Studentja e UET, Klerisa Azuni fituese e Konkursit t\u00eb Ideve t\u00eb Sip\u00ebrmarrjes s\u00eb student\u00ebve nga universitetet e Ballkanit Per\u00ebndimor"},"content":{"rendered":"<p>Konferenca p\u00ebrmbyll\u00ebse e konkursit t\u00eb ideve sip\u00ebrmarr\u00ebse u \u00a0zhvillua n\u00eb UET n\u00eb \u201cTransnational Dissemination Conference\u201d n\u00eb kuad\u00ebr t\u00eb Jav\u00ebs Nd\u00ebrkomb\u00ebtare n\u00eb Universitetin Europian t\u00eb Tiran\u00ebs, n\u00eb kuadrin e projektit Erasmus+\u00a0 e\u2013VIVA.<\/p>\n<p>Skuadra fituese e k\u00ebtij konkursi me pjes\u00ebmarr\u00ebs nga student\u00eb nga universitetet e Ballkanit Per\u00ebndimor, ishte ideja \u201cPower B\u201d, prezantuar nga Klerisa Azuni studente e komunikimit n\u00eb Universitetin Europian t\u00eb Tiran\u00ebs. \u00a0PowerB \u00ebsht\u00eb nj\u00eb pajisje e konvertimit t\u00eb energjis\u00eb mekanike n\u00eb elektrike, e l\u00ebvizshme, dhe q\u00eb mund t\u00eb p\u00ebrdoret n\u00eb nd\u00ebrprerjet e energjis\u00eb ose n\u00eb zona me munges\u00eb t\u00eb energjis\u00eb elektrike.<\/p>\n<p>&nbsp;<\/p>\n<p>Ky projekt, ku lider ishte Universiteti Europian i Tiram\u00ebs kishte nj\u00eb buxhet afro 1 milion Euro dhe p\u00ebrfshiu dhe 15 institucione t\u00eb arsimit t\u00eb lart\u00eb nga rajoni dhe Europa si; Die Berater\u00ae Unternehmensberatung GmbH \/ dB \u2013 Austri; Blended learning institutions\u2019cooperative \/ blinc eG \u2013 Gjermani; University of Duisburg Essen \u2013 Gjermani; Universidade Nova de Lisboa \u2013 Portugali;\u00a0 Cyril and Methodius University in Skopje \u2013 RMV; Mother Teresa University \u2013 RMV;\u00a0 Universiteti i Elbasanit \u201cAleksand\u00ebr Xhuvani\u201d \u2013 Shqip\u00ebri; University of Sarajevo \u2013 Bosnje &amp; Herzegovin\u00eb; University Sarajevo School of Science and Technology &#8211; Bosnje &amp; Herzegovin\u00eb; University of Donja Gorica \u2013 Mal i Zi; University of Montenegro \u2013 Mal i Zi; Universum College \u2013 Kosov\u00eb; Universiteti \u201cKadri Zeka\u201d Gjilan \u2013 Kosov\u00eb; University of Novi Sad \u2013 Serbi; University of Ni\u0161 \u2013 Serbi.<\/p>\n<p>Projekti e-VIVA synon krijimin e nj\u00eb qasjeje mix t\u00eb t\u00eb m\u00ebsuarit, p\u00ebr t\u00eb leht\u00ebsuar dhe validuar zhvillimin e kompetencave q\u00eb lidhen me sh\u00ebrbimin, n\u00eb kontekste informale t\u00eb t\u00eb m\u00ebsuarit n\u00eb universitet dhe n\u00eb vendin e pun\u00ebs. N\u00ebp\u00ebrmjet projektit e-VIVA, kompetencat e lidhura me sh\u00ebrbimimin fitohen bazuar n\u00eb: Entrecomp \u2013 skema e\u00a0 kompetencave p\u00ebr sip\u00ebrmarrjen e Komisionit Evropian; fokus i fort\u00eb te klient\u00ebt dhe nevojat e tyre; qasje inovative t\u00eb m\u00ebsimdh\u00ebnies dhe t\u00eb t\u00eb nx\u00ebnit, bazuar n\u00eb nj\u00eb qasje t\u00eb projektimit t\u00eb mendimit (Design Thinking); instrumente mikse t\u00eb m\u00ebsimdh\u00ebnies (F2F \u2013 e-learning \u2013 projekte); validimi i kompetencave p\u00ebrmes Level 5.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Konferenca p\u00ebrmbyll\u00ebse e konkursit t\u00eb ideve sip\u00ebrmarr\u00ebse u \u00a0zhvillua n\u00eb UET n\u00eb \u201cTransnational Dissemination Conference\u201d n\u00eb kuad\u00ebr t\u00eb Jav\u00ebs Nd\u00ebrkomb\u00ebtare n\u00eb Universitetin Europian t\u00eb Tiran\u00ebs, n\u00eb kuadrin e projektit Erasmus+\u00a0 e\u2013VIVA. Skuadra fituese e k\u00ebtij konkursi me pjes\u00ebmarr\u00ebs nga student\u00eb &hellip; <\/p>","protected":false},"author":1,"featured_media":13356,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-13355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-te-ndryshme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Studentja e UET, Klerisa Azuni fituese e Konkursit t\u00eb Ideve t\u00eb Sip\u00ebrmarrjes s\u00eb student\u00ebve nga universitetet e Ballkanit Per\u00ebndimor - UET<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uet.edu.al\/en\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Studentja e UET, Klerisa Azuni fituese e Konkursit t\u00eb Ideve t\u00eb Sip\u00ebrmarrjes s\u00eb student\u00ebve nga universitetet e Ballkanit Per\u00ebndimor - UET\" \/>\n<meta property=\"og:description\" content=\"Konferenca p\u00ebrmbyll\u00ebse e konkursit t\u00eb ideve sip\u00ebrmarr\u00ebse u \u00a0zhvillua n\u00eb UET n\u00eb \u201cTransnational Dissemination Conference\u201d n\u00eb kuad\u00ebr t\u00eb Jav\u00ebs Nd\u00ebrkomb\u00ebtare n\u00eb Universitetin Europian t\u00eb Tiran\u00ebs, n\u00eb kuadrin e projektit Erasmus+\u00a0 e\u2013VIVA. Skuadra fituese e k\u00ebtij konkursi me pjes\u00ebmarr\u00ebs nga student\u00eb &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uet.edu.al\/en\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/\" \/>\n<meta property=\"og:site_name\" content=\"UET\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UniversitetiEuropianiTiranes\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-05T09:53:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-05T14:25:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uet.edu.al\/wp-content\/uploads\/2022\/05\/klerisa-azuni.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uet.edu.al\\\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uet.edu.al\\\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/uet.edu.al\\\/en\\\/#\\\/schema\\\/person\\\/e0882bc49cd4b35d1e23bc03de52a227\"},\"headline\":\"Studentja e UET, Klerisa Azuni fituese e Konkursit t\u00eb Ideve t\u00eb Sip\u00ebrmarrjes s\u00eb student\u00ebve nga universitetet e Ballkanit Per\u00ebndimor\",\"datePublished\":\"2022-05-05T09:53:22+00:00\",\"dateModified\":\"2022-05-05T14:25:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uet.edu.al\\\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\\\/\"},\"wordCount\":366,\"publisher\":{\"@id\":\"https:\\\/\\\/uet.edu.al\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uet.edu.al\\\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uet.edu.al\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/klerisa-azuni.jpg\",\"articleSection\":[\"T\u00eb ndryshme\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uet.edu.al\\\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\\\/\",\"url\":\"https:\\\/\\\/uet.edu.al\\\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\\\/\",\"name\":\"Studentja e UET, Klerisa Azuni fituese e Konkursit t\u00eb Ideve t\u00eb Sip\u00ebrmarrjes s\u00eb student\u00ebve nga universitetet e Ballkanit Per\u00ebndimor - UET\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uet.edu.al\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uet.edu.al\\\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uet.edu.al\\\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uet.edu.al\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/klerisa-azuni.jpg\",\"datePublished\":\"2022-05-05T09:53:22+00:00\",\"dateModified\":\"2022-05-05T14:25:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uet.edu.al\\\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uet.edu.al\\\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uet.edu.al\\\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uet.edu.al\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/klerisa-azuni.jpg\",\"contentUrl\":\"https:\\\/\\\/uet.edu.al\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/klerisa-azuni.jpg\",\"width\":1280,\"height\":853,\"caption\":\"Klerisa Azuni studente e komunikimit n\u00eb Universitetin Europian t\u00eb Tiran\u00ebs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uet.edu.al\\\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uet.edu.al\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Studentja e UET, Klerisa Azuni fituese e Konkursit t\u00eb Ideve t\u00eb Sip\u00ebrmarrjes s\u00eb student\u00ebve nga universitetet e Ballkanit Per\u00ebndimor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uet.edu.al\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/uet.edu.al\\\/en\\\/\",\"name\":\"UET\",\"description\":\"Universiteti Europian i Tiran\u00ebs\",\"publisher\":{\"@id\":\"https:\\\/\\\/uet.edu.al\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uet.edu.al\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uet.edu.al\\\/en\\\/#organization\",\"name\":\"Universiteti Europian i Tiranes\",\"url\":\"https:\\\/\\\/uet.edu.al\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uet.edu.al\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uet.edu.al\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Logo-pa-adrese.png\",\"contentUrl\":\"https:\\\/\\\/uet.edu.al\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Logo-pa-adrese.png\",\"width\":1418,\"height\":696,\"caption\":\"Universiteti Europian i Tiranes\"},\"image\":{\"@id\":\"https:\\\/\\\/uet.edu.al\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UniversitetiEuropianiTiranes\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uet.edu.al\\\/en\\\/#\\\/schema\\\/person\\\/e0882bc49cd4b35d1e23bc03de52a227\",\"name\":\"admin\",\"sameAs\":[\"https:\\\/\\\/uet.edu.al\"],\"url\":\"https:\\\/\\\/uet.edu.al\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Studentja e UET, Klerisa Azuni fituese e Konkursit t\u00eb Ideve t\u00eb Sip\u00ebrmarrjes s\u00eb student\u00ebve nga universitetet e Ballkanit Per\u00ebndimor - UET","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uet.edu.al\/en\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/","og_locale":"en_US","og_type":"article","og_title":"Studentja e UET, Klerisa Azuni fituese e Konkursit t\u00eb Ideve t\u00eb Sip\u00ebrmarrjes s\u00eb student\u00ebve nga universitetet e Ballkanit Per\u00ebndimor - UET","og_description":"Konferenca p\u00ebrmbyll\u00ebse e konkursit t\u00eb ideve sip\u00ebrmarr\u00ebse u \u00a0zhvillua n\u00eb UET n\u00eb \u201cTransnational Dissemination Conference\u201d n\u00eb kuad\u00ebr t\u00eb Jav\u00ebs Nd\u00ebrkomb\u00ebtare n\u00eb Universitetin Europian t\u00eb Tiran\u00ebs, n\u00eb kuadrin e projektit Erasmus+\u00a0 e\u2013VIVA. Skuadra fituese e k\u00ebtij konkursi me pjes\u00ebmarr\u00ebs nga student\u00eb &hellip;","og_url":"https:\/\/uet.edu.al\/en\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/","og_site_name":"UET","article_publisher":"https:\/\/www.facebook.com\/UniversitetiEuropianiTiranes\/","article_published_time":"2022-05-05T09:53:22+00:00","article_modified_time":"2022-05-05T14:25:46+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/uet.edu.al\/wp-content\/uploads\/2022\/05\/klerisa-azuni.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uet.edu.al\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/#article","isPartOf":{"@id":"https:\/\/uet.edu.al\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/"},"author":{"name":"admin","@id":"https:\/\/uet.edu.al\/en\/#\/schema\/person\/e0882bc49cd4b35d1e23bc03de52a227"},"headline":"Studentja e UET, Klerisa Azuni fituese e Konkursit t\u00eb Ideve t\u00eb Sip\u00ebrmarrjes s\u00eb student\u00ebve nga universitetet e Ballkanit Per\u00ebndimor","datePublished":"2022-05-05T09:53:22+00:00","dateModified":"2022-05-05T14:25:46+00:00","mainEntityOfPage":{"@id":"https:\/\/uet.edu.al\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/"},"wordCount":366,"publisher":{"@id":"https:\/\/uet.edu.al\/en\/#organization"},"image":{"@id":"https:\/\/uet.edu.al\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/#primaryimage"},"thumbnailUrl":"https:\/\/uet.edu.al\/wp-content\/uploads\/2022\/05\/klerisa-azuni.jpg","articleSection":["T\u00eb ndryshme"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/uet.edu.al\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/","url":"https:\/\/uet.edu.al\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/","name":"Studentja e UET, Klerisa Azuni fituese e Konkursit t\u00eb Ideve t\u00eb Sip\u00ebrmarrjes s\u00eb student\u00ebve nga universitetet e Ballkanit Per\u00ebndimor - UET","isPartOf":{"@id":"https:\/\/uet.edu.al\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uet.edu.al\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/#primaryimage"},"image":{"@id":"https:\/\/uet.edu.al\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/#primaryimage"},"thumbnailUrl":"https:\/\/uet.edu.al\/wp-content\/uploads\/2022\/05\/klerisa-azuni.jpg","datePublished":"2022-05-05T09:53:22+00:00","dateModified":"2022-05-05T14:25:46+00:00","breadcrumb":{"@id":"https:\/\/uet.edu.al\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uet.edu.al\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uet.edu.al\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/#primaryimage","url":"https:\/\/uet.edu.al\/wp-content\/uploads\/2022\/05\/klerisa-azuni.jpg","contentUrl":"https:\/\/uet.edu.al\/wp-content\/uploads\/2022\/05\/klerisa-azuni.jpg","width":1280,"height":853,"caption":"Klerisa Azuni studente e komunikimit n\u00eb Universitetin Europian t\u00eb Tiran\u00ebs"},{"@type":"BreadcrumbList","@id":"https:\/\/uet.edu.al\/klerisa-azuni-studente-e-komunikimit-ne-uet-fituese-e-konkursit-te-ideve-te-sipermarrjes-se-studenteve-nga-universitetet-e-ballkanit-perendimor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uet.edu.al\/"},{"@type":"ListItem","position":2,"name":"Studentja e UET, Klerisa Azuni fituese e Konkursit t\u00eb Ideve t\u00eb Sip\u00ebrmarrjes s\u00eb student\u00ebve nga universitetet e Ballkanit Per\u00ebndimor"}]},{"@type":"WebSite","@id":"https:\/\/uet.edu.al\/en\/#website","url":"https:\/\/uet.edu.al\/en\/","name":"UET","description":"Universiteti Europian i Tiran\u00ebs","publisher":{"@id":"https:\/\/uet.edu.al\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uet.edu.al\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/uet.edu.al\/en\/#organization","name":"Universiteti Europian i Tiranes","url":"https:\/\/uet.edu.al\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uet.edu.al\/en\/#\/schema\/logo\/image\/","url":"https:\/\/uet.edu.al\/wp-content\/uploads\/2022\/12\/Logo-pa-adrese.png","contentUrl":"https:\/\/uet.edu.al\/wp-content\/uploads\/2022\/12\/Logo-pa-adrese.png","width":1418,"height":696,"caption":"Universiteti Europian i Tiranes"},"image":{"@id":"https:\/\/uet.edu.al\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UniversitetiEuropianiTiranes\/"]},{"@type":"Person","@id":"https:\/\/uet.edu.al\/en\/#\/schema\/person\/e0882bc49cd4b35d1e23bc03de52a227","name":"admin","sameAs":["https:\/\/uet.edu.al"],"url":"https:\/\/uet.edu.al\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/uet.edu.al\/en\/wp-json\/wp\/v2\/posts\/13355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uet.edu.al\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uet.edu.al\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uet.edu.al\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uet.edu.al\/en\/wp-json\/wp\/v2\/comments?post=13355"}],"version-history":[{"count":4,"href":"https:\/\/uet.edu.al\/en\/wp-json\/wp\/v2\/posts\/13355\/revisions"}],"predecessor-version":[{"id":13361,"href":"https:\/\/uet.edu.al\/en\/wp-json\/wp\/v2\/posts\/13355\/revisions\/13361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uet.edu.al\/en\/wp-json\/wp\/v2\/media\/13356"}],"wp:attachment":[{"href":"https:\/\/uet.edu.al\/en\/wp-json\/wp\/v2\/media?parent=13355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uet.edu.al\/en\/wp-json\/wp\/v2\/categories?post=13355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uet.edu.al\/en\/wp-json\/wp\/v2\/tags?post=13355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}